{"id":419,"date":"2025-01-25T18:20:09","date_gmt":"2025-01-25T17:20:09","guid":{"rendered":"http:\/\/electricistaelcampello.es\/?post_type=cea_service&#038;p=419"},"modified":"2025-01-25T18:20:09","modified_gmt":"2025-01-25T17:20:09","slug":"uberprufung-der-elektroinstallation","status":"publish","type":"cea_service","link":"http:\/\/electricistaelcampello.es\/de\/cea_service\/revisiones-de-instalaciones-electricas\/","title":{"rendered":"Pr\u00fcfungen der Elektroinstallation"},"content":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"template":"","cea_service_category":[],"class_list":["post-419","cea_service","type-cea_service","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Revisi\u00f3nes de Instalaci\u00f3nes El\u00e9ctricas - Williams Electrics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/electricistaelcampello.es\/de\/cea_dienst\/uberprufung-der-elektroinstallation\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Revisi\u00f3nes de Instalaci\u00f3nes El\u00e9ctricas - Williams Electrics\" \/>\n<meta property=\"og:url\" content=\"https:\/\/electricistaelcampello.es\/de\/cea_dienst\/uberprufung-der-elektroinstallation\/\" \/>\n<meta property=\"og:site_name\" content=\"Williams Electrics\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61572624609208\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/electricistaelcampello.es\\\/cea_service\\\/revisiones-de-instalaciones-electricas\\\/\",\"url\":\"https:\\\/\\\/electricistaelcampello.es\\\/cea_service\\\/revisiones-de-instalaciones-electricas\\\/\",\"name\":\"Revisi\u00f3nes de Instalaci\u00f3nes El\u00e9ctricas - Williams Electrics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/electricistaelcampello.es\\\/#website\"},\"datePublished\":\"2025-01-25T17:20:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/electricistaelcampello.es\\\/cea_service\\\/revisiones-de-instalaciones-electricas\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/electricistaelcampello.es\\\/cea_service\\\/revisiones-de-instalaciones-electricas\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/electricistaelcampello.es\\\/cea_service\\\/revisiones-de-instalaciones-electricas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/electricistaelcampello.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services\",\"item\":\"https:\\\/\\\/electricistaelcampello.es\\\/cea_service\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Revisi\u00f3nes de Instalaci\u00f3nes El\u00e9ctricas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/electricistaelcampello.es\\\/#website\",\"url\":\"https:\\\/\\\/electricistaelcampello.es\\\/\",\"name\":\"Williams Electrics\",\"description\":\"Empresa Instaladora El\u00e9ctrica \\\/ Baja Tension\",\"publisher\":{\"@id\":\"https:\\\/\\\/electricistaelcampello.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/electricistaelcampello.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/electricistaelcampello.es\\\/#organization\",\"name\":\"Williams Electrics\",\"url\":\"https:\\\/\\\/electricistaelcampello.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/electricistaelcampello.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/electricistaelcampello.es\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/small-web-logoo.png\",\"contentUrl\":\"https:\\\/\\\/electricistaelcampello.es\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/small-web-logoo.png\",\"width\":375,\"height\":91,\"caption\":\"Williams Electrics\"},\"image\":{\"@id\":\"https:\\\/\\\/electricistaelcampello.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61572624609208\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00dcberholung von Elektroinstallationen - Williams Electrics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/electricistaelcampello.es\/de\/cea_dienst\/uberprufung-der-elektroinstallation\/","og_locale":"de_DE","og_type":"article","og_title":"Revisi\u00f3nes de Instalaci\u00f3nes El\u00e9ctricas - Williams Electrics","og_url":"https:\/\/electricistaelcampello.es\/de\/cea_dienst\/uberprufung-der-elektroinstallation\/","og_site_name":"Williams Electrics","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61572624609208","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/electricistaelcampello.es\/cea_service\/revisiones-de-instalaciones-electricas\/","url":"https:\/\/electricistaelcampello.es\/cea_service\/revisiones-de-instalaciones-electricas\/","name":"\u00dcberholung von Elektroinstallationen - Williams Electrics","isPartOf":{"@id":"https:\/\/electricistaelcampello.es\/#website"},"datePublished":"2025-01-25T17:20:09+00:00","breadcrumb":{"@id":"https:\/\/electricistaelcampello.es\/cea_service\/revisiones-de-instalaciones-electricas\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/electricistaelcampello.es\/cea_service\/revisiones-de-instalaciones-electricas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/electricistaelcampello.es\/cea_service\/revisiones-de-instalaciones-electricas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/electricistaelcampello.es\/"},{"@type":"ListItem","position":2,"name":"Services","item":"https:\/\/electricistaelcampello.es\/cea_service\/"},{"@type":"ListItem","position":3,"name":"Revisi\u00f3nes de Instalaci\u00f3nes El\u00e9ctricas"}]},{"@type":"WebSite","@id":"https:\/\/electricistaelcampello.es\/#website","url":"https:\/\/electricistaelcampello.es\/","name":"Williams Elektrik","description":"Elektroinstallationsunternehmen \/ Niederspannung","publisher":{"@id":"https:\/\/electricistaelcampello.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/electricistaelcampello.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/electricistaelcampello.es\/#organization","name":"Williams Elektrik","url":"https:\/\/electricistaelcampello.es\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/electricistaelcampello.es\/#\/schema\/logo\/image\/","url":"https:\/\/electricistaelcampello.es\/wp-content\/uploads\/2025\/02\/small-web-logoo.png","contentUrl":"https:\/\/electricistaelcampello.es\/wp-content\/uploads\/2025\/02\/small-web-logoo.png","width":375,"height":91,"caption":"Williams Electrics"},"image":{"@id":"https:\/\/electricistaelcampello.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61572624609208"]}]}},"_links":{"self":[{"href":"http:\/\/electricistaelcampello.es\/de\/wp-json\/wp\/v2\/cea_service\/419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/electricistaelcampello.es\/de\/wp-json\/wp\/v2\/cea_service"}],"about":[{"href":"http:\/\/electricistaelcampello.es\/de\/wp-json\/wp\/v2\/types\/cea_service"}],"author":[{"embeddable":true,"href":"http:\/\/electricistaelcampello.es\/de\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"http:\/\/electricistaelcampello.es\/de\/wp-json\/wp\/v2\/media?parent=419"}],"wp:term":[{"taxonomy":"cea_service_category","embeddable":true,"href":"http:\/\/electricistaelcampello.es\/de\/wp-json\/wp\/v2\/cea_service_category?post=419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}